{"id":813,"date":"2020-12-21T14:03:29","date_gmt":"2020-12-21T12:03:29","guid":{"rendered":"https:\/\/olfilprom.md\/product\/import-placeholder-for-7622\/"},"modified":"2022-01-06T15:39:29","modified_gmt":"2022-01-06T13:39:29","slug":"disc-diamant-wave-115-10-buc-min-rrt115","status":"publish","type":"product","link":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/","title":{"rendered":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":833,"template":"","meta":[],"product_brand":[],"product_cat":[41],"product_tag":[],"class_list":{"0":"post-813","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-discuri-de-diamant-rodex","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/\" \/>\n<meta property=\"og:site_name\" content=\"olfilprom.md\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olfilprom.md\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-06T13:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Rodex-RRT-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/\",\"name\":\"Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Rodex-RRT-1.jpg\",\"datePublished\":\"2020-12-21T12:03:29+00:00\",\"dateModified\":\"2022-01-06T13:39:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Rodex-RRT-1.jpg\",\"contentUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Rodex-RRT-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Disc diamant Wave 115, Rodex, 10 buc min, RRT115\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/almaznye-diski-rodex\\\/disc-diamant-wave-115-10-buc-min-rrt115\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0430\u0433\u0430\u0437\u0438\u043d\",\"item\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Disc diamant Wave 115, Rodex, 10 buc min, RRT115\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\",\"name\":\"olfilprom.md\",\"description\":\"Vanzarea angro si cu amanuntul a instrumentelor si a materialelor | olfilprom.md\",\"publisher\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#organization\",\"name\":\"Olfilprom\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/olfilprom-logo-250-250.jpg\",\"contentUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/olfilprom-logo-250-250.jpg\",\"width\":250,\"height\":250,\"caption\":\"Olfilprom\"},\"image\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olfilprom.md\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/","og_locale":"ru_RU","og_type":"article","og_title":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md","og_url":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/","og_site_name":"olfilprom.md","article_publisher":"https:\/\/www.facebook.com\/olfilprom.md\/","article_modified_time":"2022-01-06T13:39:29+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Rodex-RRT-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/","url":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/","name":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115 - olfilprom.md","isPartOf":{"@id":"https:\/\/olfilprom.md\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/#primaryimage"},"image":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/#primaryimage"},"thumbnailUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Rodex-RRT-1.jpg","datePublished":"2020-12-21T12:03:29+00:00","dateModified":"2022-01-06T13:39:29+00:00","breadcrumb":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/#primaryimage","url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Rodex-RRT-1.jpg","contentUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Rodex-RRT-1.jpg","width":500,"height":500,"caption":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115"},{"@type":"BreadcrumbList","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/almaznye-diski-rodex\/disc-diamant-wave-115-10-buc-min-rrt115\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/olfilprom.md\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d","item":"https:\/\/olfilprom.md\/ru\/magazin\/"},{"@type":"ListItem","position":3,"name":"Disc diamant Wave 115, Rodex, 10 buc min, RRT115"}]},{"@type":"WebSite","@id":"https:\/\/olfilprom.md\/ru\/#website","url":"https:\/\/olfilprom.md\/ru\/","name":"olfilprom.md","description":"Vanzarea angro si cu amanuntul a instrumentelor si a materialelor | olfilprom.md","publisher":{"@id":"https:\/\/olfilprom.md\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olfilprom.md\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/olfilprom.md\/ru\/#organization","name":"Olfilprom","url":"https:\/\/olfilprom.md\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/olfilprom.md\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/olfilprom-logo-250-250.jpg","contentUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/olfilprom-logo-250-250.jpg","width":250,"height":250,"caption":"Olfilprom"},"image":{"@id":"https:\/\/olfilprom.md\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olfilprom.md\/"]}]}},"_links":{"self":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/media\/833"}],"wp:attachment":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_brand?post=813"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_cat?post=813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_tag?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}