{"id":767,"date":"2020-12-21T14:03:21","date_gmt":"2020-12-21T12:03:21","guid":{"rendered":"https:\/\/olfilprom.md\/product\/import-placeholder-for-7584\/"},"modified":"2021-10-12T00:05:40","modified_gmt":"2021-10-11T21:05:40","slug":"disc-petala-125x22-100-pzf10125","status":"publish","type":"product","link":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/","title":{"rendered":"Disc petala 125&#215;22 #100, PZF10125"},"content":{"rendered":"<p>\u041a\u0440\u0443\u0433\u0438 \u043b\u0435\u043f\u0435\u0441\u0442\u043a\u043e\u0432\u044b\u0435 \u043f\u0440\u0435\u0434\u043d\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u044b \u0434\u043b\u044f \u0443\u0434\u0430\u043b\u0435\u043d\u0438\u044f \u043e\u043a\u0430\u043b\u0438\u043d\u044b \u0438 \u0437\u0430\u0443\u0441\u0435\u043d\u0435\u0446, \u0437\u0430\u0447\u0438\u0441\u0442\u043a\u0438 \u043a\u0440\u043e\u043c\u043e\u043a, \u0448\u0432\u044b \u0434\u0435\u0442\u0430\u043b\u0435\u0439 \u0438 \u043a\u043e\u043d\u0441\u0442\u0440\u0443\u043a\u0446\u0438\u0439 \u0438\u0437 \u043c\u0435\u0442\u0430\u043b\u043b\u0430, \u043d\u0435\u0440\u0436\u0430\u0432\u0435\u044e\u0449\u0435\u0439 \u0441\u0442\u0430\u043b\u0438, \u0446\u0432\u0435\u0442\u043d\u044b\u0445 \u043c\u0435\u0442\u0430\u043b\u043b\u043e\u0432, \u0430\u043b\u044e\u043c\u0438\u043d\u0438\u044f, \u0434\u0440\u0435\u0432\u0435\u0441\u0438\u043d\u044b, \u043f\u043b\u0430\u0441\u0442\u0438\u043a\u0430 \u0438 \u0434\u043e\u0432\u043e\u0434\u043a\u0438 \u043f\u043e\u0432\u0435\u0440\u0445\u043d\u043e\u0441\u0442\u0435\u0439.<\/p>\n<p>\u041a\u0440\u0443\u0433\u0438 \u043e\u0442\u0440\u0435\u0437\u043d\u044b\u0435 \u0438\u0437\u0433\u043e\u0442\u0430\u0432\u043b\u0438\u0432\u0430\u044e\u0442\u0441\u044f \u0438\u0437 \u0430\u0431\u0440\u0430\u0437\u0438\u0432\u043d\u043e\u0439 \u0448\u043a\u0443\u0440\u043a\u0438 \u043d\u0430 \u0442\u043a\u0430\u043d\u0435\u0432\u043e\u0439 \u043e\u0441\u043d\u043e\u0432\u0435 \u0438\u0437 \u044d\u043b\u0435\u043a\u0442\u0440\u043e\u043a\u043e\u0440\u0443\u043d\u0434\u0430.<br \/>\n\u041b\u0435\u043f\u0435\u0441\u0442\u043a\u0438 \u0440\u0430\u0437\u043c\u0435\u0449\u0435\u043d\u044b \u0432\u0435\u0435\u0440\u043e\u043e\u0431\u0440\u0430\u0437\u043d\u043e, \u0440\u0430\u0434\u0438\u0430\u043b\u044c\u043d\u043e, \u0431\u043b\u0430\u0433\u043e\u0434\u044f\u0440\u044f \u0447\u0435\u043c\u0443 \u043a\u0440\u0443\u0433\u0438 \u0438\u043c\u0435\u044e\u0442 \u0432\u044b\u0441\u043e\u043a\u0443\u044e \u043f\u0440\u043e\u0438\u0437\u0432\u043e\u0434\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c \u0438 \u044d\u043b\u0430\u0441\u0442\u0438\u0447\u043d\u043e\u0441\u0442\u044c \u043f\u0440\u0438 \u0448\u043b\u0438\u0444\u043e\u0432\u043a\u0435.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disc lamelar pentru slefuit.<br \/>\nDiametru 125 \u0445 22mm.<br \/>\nGranulatie #100.<br \/>\nMaterial de lucru: otel, lemn.<\/p>\n","protected":false},"featured_media":789,"template":"","meta":[],"product_brand":[],"product_cat":[40],"product_tag":[],"class_list":{"0":"post-767","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-discuri-petala","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Disc petala 125x22 #100, PZF10125 - olfilprom.md<\/title>\n<meta name=\"description\" content=\"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disc petala 125x22 #100, PZF10125 - olfilprom.md\" \/>\n<meta property=\"og:description\" content=\"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/\" \/>\n<meta property=\"og:site_name\" content=\"olfilprom.md\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olfilprom.md\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-11T21:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Pegatek-PZF-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/\",\"name\":\"Disc petala 125x22 #100, PZF10125 - olfilprom.md\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Pegatek-PZF-1.jpg\",\"datePublished\":\"2020-12-21T12:03:21+00:00\",\"dateModified\":\"2021-10-11T21:05:40+00:00\",\"description\":\"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/#primaryimage\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Pegatek-PZF-1.jpg\",\"contentUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Disc-Pegatek-PZF-1.jpg\",\"width\":600,\"height\":600,\"caption\":\"Disc petala 125&#215;22 #100, PZF10125\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/abrazivnye-diski\\\/lepestkovye-diski\\\/disc-petala-125x22-100-pzf10125\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0430\u0433\u0430\u0437\u0438\u043d\",\"item\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Disc petala 125&#215;22 #100, PZF10125\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\",\"name\":\"olfilprom.md\",\"description\":\"Vanzarea angro si cu amanuntul a instrumentelor si a materialelor | olfilprom.md\",\"publisher\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#organization\",\"name\":\"Olfilprom\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/olfilprom-logo-250-250.jpg\",\"contentUrl\":\"https:\\\/\\\/olfilprom.md\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/olfilprom-logo-250-250.jpg\",\"width\":250,\"height\":250,\"caption\":\"Olfilprom\"},\"image\":{\"@id\":\"https:\\\/\\\/olfilprom.md\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/olfilprom.md\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disc petala 125x22 #100, PZF10125 - olfilprom.md","description":"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/","og_locale":"ru_RU","og_type":"article","og_title":"Disc petala 125x22 #100, PZF10125 - olfilprom.md","og_description":"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.","og_url":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/","og_site_name":"olfilprom.md","article_publisher":"https:\/\/www.facebook.com\/olfilprom.md\/","article_modified_time":"2021-10-11T21:05:40+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Pegatek-PZF-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/","url":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/","name":"Disc petala 125x22 #100, PZF10125 - olfilprom.md","isPartOf":{"@id":"https:\/\/olfilprom.md\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/#primaryimage"},"image":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/#primaryimage"},"thumbnailUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Pegatek-PZF-1.jpg","datePublished":"2020-12-21T12:03:21+00:00","dateModified":"2021-10-11T21:05:40+00:00","description":"Disc lamelar pentru slefuit. Diametru 125 \u0445 22mm. Granulatie #100. Material de lucru: otel, lemn.","breadcrumb":{"@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/#primaryimage","url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Pegatek-PZF-1.jpg","contentUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/Disc-Pegatek-PZF-1.jpg","width":600,"height":600,"caption":"Disc petala 125&#215;22 #100, PZF10125"},{"@type":"BreadcrumbList","@id":"https:\/\/olfilprom.md\/ru\/abrazivnye-diski\/lepestkovye-diski\/disc-petala-125x22-100-pzf10125\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/olfilprom.md\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d","item":"https:\/\/olfilprom.md\/ru\/magazin\/"},{"@type":"ListItem","position":3,"name":"Disc petala 125&#215;22 #100, PZF10125"}]},{"@type":"WebSite","@id":"https:\/\/olfilprom.md\/ru\/#website","url":"https:\/\/olfilprom.md\/ru\/","name":"olfilprom.md","description":"Vanzarea angro si cu amanuntul a instrumentelor si a materialelor | olfilprom.md","publisher":{"@id":"https:\/\/olfilprom.md\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/olfilprom.md\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/olfilprom.md\/ru\/#organization","name":"Olfilprom","url":"https:\/\/olfilprom.md\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/olfilprom.md\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/olfilprom-logo-250-250.jpg","contentUrl":"https:\/\/olfilprom.md\/wp-content\/uploads\/2020\/12\/olfilprom-logo-250-250.jpg","width":250,"height":250,"caption":"Olfilprom"},"image":{"@id":"https:\/\/olfilprom.md\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/olfilprom.md\/"]}]}},"_links":{"self":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/media\/789"}],"wp:attachment":[{"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_brand?post=767"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_cat?post=767"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/olfilprom.md\/ru\/wp-json\/wp\/v2\/product_tag?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}